{"id":17098,"date":"2025-02-21T07:49:19","date_gmt":"2025-02-21T07:49:19","guid":{"rendered":"https:\/\/www.ionzabalegui.com\/make-an-appointment\/"},"modified":"2025-12-29T11:48:57","modified_gmt":"2025-12-29T11:48:57","slug":"make-an-appointment","status":"publish","type":"page","link":"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(27,45,71,0.2)&#8221; background_image=&#8221;https:\/\/www.ionzabalegui.com\/wp-content\/uploads\/2025\/03\/Cita-Previa-Zabalegui_Mesa-de-trabajo-1.webp&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;164px||123px||false|false&#8221; custom_padding_tablet=&#8221;164px||28px||false|false&#8221; custom_padding_phone=&#8221;100px||50px||false|false&#8221; border_radii=&#8221;off|||40px|40px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;37px|auto||auto||&#8221; custom_padding=&#8221;0px|||||&#8221; animation_style=&#8221;slide&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; header_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#d9e3c5&#8243; header_font_size=&#8221;80px&#8221; width=&#8221;75%&#8221; width_tablet=&#8221;75%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; header_font_size_tablet=&#8221;80px&#8221; header_font_size_phone=&#8221;60px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; inline_fonts=&#8221;Spectral&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Make an appointment<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 0%|#f9f9f9 100%&#8221; custom_margin=&#8221;||-50px||false|false&#8221; custom_padding=&#8221;82px||83px|||&#8221; custom_padding_tablet=&#8221;82px||83px|||&#8221; custom_padding_phone=&#8221;50px||50px||true|false&#8221; border_radii=&#8221;off|||50px|50px&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1600px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Spectral||||||||&#8221; text_text_color=&#8221;#d9e3c5&#8243; text_font_size=&#8221;45px&#8221; text_line_height=&#8221;1.3em&#8221; header_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; header_2_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; header_2_text_color=&#8221;#1b2d47&#8243; header_2_font_size=&#8221;45px&#8221; custom_margin=&#8221;||17px|||&#8221; header_text_align_tablet=&#8221;&#8221; header_text_align_phone=&#8221;&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #1b2d47;\">Contact us<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<p><span style=%22color: #1b2d47;%22>Consult us if you have periodontal problems, need an implant, or require a professional with extensive experience. Or call us at: <\/span><\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p><span style=%22color: #1b2d47;%22>Please contact us if you have periodontal problems, require an implant, or need a professional with extensive experience.<\/span><\/p>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"color: #1b2d47;\">Consult us if you have periodontal problems, need an implant, or require a professional with extensive experience. Or call us at: <\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;tel:+34944231608&#8243; button_text=&#8221;Call now&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#1b2d47&#8243; button_bg_color=&#8221;#d9e3c5&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;50px&#8221; button_font=&#8221;&#8211;et_global_heading_font|||on|||||&#8221; button_icon=&#8221;&#xf879;||fa||900&#8243; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; custom_padding=&#8221;8px|20px|8px|40px|true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/wa.me\/34630471185&#8243; button_text=&#8221;Whatsapp&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#1b2d47&#8243; button_bg_color=&#8221;#d9e3c5&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;50px&#8221; button_font=&#8221;&#8211;et_global_heading_font|||on|||||&#8221; button_icon=&#8221;&#xf232;||fa||400&#8243; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; custom_padding=&#8221;8px|20px|8px|40px|true|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf879;||fa||900&#8243; icon_color=&#8221;#1b2d47&#8243; image_icon_background_color=&#8221;#d9e3c5&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;21px&#8221; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;22px&#8221; body_line_height=&#8221;1.6em&#8221; image_icon_custom_padding=&#8221;8px|8px|8px|8px|true|true&#8221; custom_margin=&#8221;||21px|-23px|false|false&#8221; custom_margin_tablet=&#8221;||21px|-80px|false|false&#8221; custom_margin_phone=&#8221;|||0px|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|||0px|false|false&#8221; border_radii_image=&#8221;on|50px|50px|50px|50px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"color: #1b2d47;\">+34 944 231 608<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf232;||fa||400&#8243; icon_color=&#8221;#1b2d47&#8243; image_icon_background_color=&#8221;#d9e3c5&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;21px&#8221; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;22px&#8221; body_line_height=&#8221;1.6em&#8221; image_icon_custom_padding=&#8221;8px|8px|8px|8px|true|true&#8221; custom_margin=&#8221;||39px|-23px|false|false&#8221; custom_margin_tablet=&#8221;||39px|-80px|false|false&#8221; custom_margin_phone=&#8221;|||0px|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|||0px|false|false&#8221; hover_enabled=&#8221;0&#8243; border_radii_image=&#8221;on|50px|50px|50px|50px&#8221; global_colors_info=&#8221;{}&#8221; url=&#8221;https:\/\/wa.me\/34630471185&#8243; link_option_url=&#8221;https:\/\/wa.me\/34630471185&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span style=\"color: #1b2d47;\">+34 630 471 185<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;17px&#8221; background_color=&#8221;#1b2d47&#8243; width=&#8221;93%&#8221; custom_padding=&#8221;15px|20px|15px|20px|true|false&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Continuous telephone service Monday to Friday from 8:00 a.m. to 8:00 p.m.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_free_form=&#8221;.wpcf7-list-item-label{||  color:#1b2d47;||  font-weight:600;||}&#8221; global_colors_info=&#8221;{}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f17216-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"17216\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/17098#wpcf7-f17216-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"17216\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f17216-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"nombreformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"campoformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"campoformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-589\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"tel-589\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"textoformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div style=\"font-family: Open Sans; font-size: 14px; font-weight: 400; color: white!important; margin-top: 10px; margin-bottom: 10px;\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-228\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-228\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read and accept the<a href=\"https:\/\/www.ionzabalegui.com\/en\/privacy-policy\/\" style=\"color: #d9e3c5\"> Privacy Policy.<\/a><\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div style=\"font-family: Open Sans; font-size: 14px; font-weight: 400; color: white!important; margin-top: 10px; margin-bottom: 10px;\">\n\t<p>We will only use your data to respond to your query or schedule a visit. We will not use it for advertising purposes.\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"243\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e5e5e5&#8243; custom_padding=&#8221;149px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1600px&#8221; min_height=&#8221;533.8px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;410.8px&#8221; custom_margin=&#8221;-1px||-1px||true|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2905.3644400760304!2d-2.9301705233625674!3d43.26474027746795!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd4e4fc545555555%3A0xc405a68a91ec8ff1!2sZabalegui%20Medicina%20Dental%20y%20Facial!5e0!3m2!1ses!2ses!4v1740125588026!5m2!1ses!2ses\" width=\"800\" height=\"450\" style=\"border:0; border-radius:20px\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|||on|||||&#8221; text_text_color=&#8221;#909266&#8243; text_font_size=&#8221;20px&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;33px||26px|||&#8221; hover_enabled=&#8221;0&#8243; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>How to get to us<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Spectral||||||||&#8221; text_text_color=&#8221;#1b2d47&#8243; text_font_size=&#8221;45px&#8221; header_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; header_2_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; header_2_text_color=&#8221;#1b2d47&#8243; header_2_font_size=&#8221;45px&#8221; custom_margin=&#8221;||||false|false&#8221; text_line_height_tablet=&#8221;&#8221; text_line_height_phone=&#8221;1.1em&#8221; text_line_height_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Zabalegui Dental Clinic<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_text_color=&#8221;#1b2d47&#8243; text_font_size=&#8221;16px&#8221; text_orientation_tablet=&#8221;&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>We are located in a central area, next to Jardines de Albia and <strong>two minutes from one of the city&#8217;s most important thoroughfares<\/strong>, Gran V\u00eda, with nearby parking and Metro stops.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;16521,16574,16534,16589,16604,16559,16608,16506&#8243; posts_number=&#8221;8&#8243; show_title_and_caption=&#8221;off&#8221; show_pagination=&#8221;off&#8221; zoom_icon_color=&#8221;#d9e3c5&#8243; hover_overlay_color=&#8221;rgba(27,45,71,0.28)&#8221; hover_icon=&#8221;T||divi||400&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;16521,16574,16534,16589,16604,16559,16608,16506&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Make an appointmentContact usConsult us if you have periodontal problems, need an implant, or require a professional with extensive experience. Or call us at: +34 944 231 608+34 630 471 185Continuous telephone service Monday to Friday from 8:00 a.m. to 8:00 p.m.\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f17216-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"17216\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/17098#wpcf7-f17216-o2\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"17216\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f17216-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"nombreformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"campoformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"campoformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-589\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"tel-589\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"textoformulario\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div style=\"font-family: Open Sans; font-size: 14px; font-weight: 400; color: white!important; margin-top: 10px; margin-bottom: 10px;\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-228\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-228\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read and accept the<a href=\"https:\/\/www.ionzabalegui.com\/en\/privacy-policy\/\" style=\"color: #d9e3c5\"> Privacy Policy.<\/a><\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div style=\"font-family: Open Sans; font-size: 14px; font-weight: 400; color: white!important; margin-top: 10px; margin-bottom: 10px;\">\n\t<p>We will only use your data to respond to your query or schedule a visit. We will not use it for advertising purposes.\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"3\"\/><script>\ndocument.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\nHow to get to usZabalegui Dental ClinicWe are located in a central [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17098","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Bilbao Dental Clinic | Ion Zabalegui<\/title>\n<meta name=\"description\" content=\"Dental Implants in Bilbao. Zabalegui Dental Clinic. Cosmetic Dentistry and Periodontics in Bilbao. Microsurgery and technology. Ion Zabalegui.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Bilbao Dental Clinic | Ion Zabalegui\" \/>\n<meta property=\"og:description\" content=\"Dental Implants in Bilbao. Zabalegui Dental Clinic. Cosmetic Dentistry and Periodontics in Bilbao. Microsurgery and technology. Ion Zabalegui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/\" \/>\n<meta property=\"og:site_name\" content=\"Zabalegui\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T11:48:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Bilbao Dental Clinic | Ion Zabalegui","description":"Dental Implants in Bilbao. Zabalegui Dental Clinic. Cosmetic Dentistry and Periodontics in Bilbao. Microsurgery and technology. Ion Zabalegui.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Contact Bilbao Dental Clinic | Ion Zabalegui","og_description":"Dental Implants in Bilbao. Zabalegui Dental Clinic. Cosmetic Dentistry and Periodontics in Bilbao. Microsurgery and technology. Ion Zabalegui.","og_url":"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/","og_site_name":"Zabalegui","article_modified_time":"2025-12-29T11:48:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/","url":"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/","name":"Contact Bilbao Dental Clinic | Ion Zabalegui","isPartOf":{"@id":"https:\/\/www.ionzabalegui.com\/en\/#website"},"datePublished":"2025-02-21T07:49:19+00:00","dateModified":"2025-12-29T11:48:57+00:00","description":"Dental Implants in Bilbao. Zabalegui Dental Clinic. Cosmetic Dentistry and Periodontics in Bilbao. Microsurgery and technology. Ion Zabalegui.","breadcrumb":{"@id":"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ionzabalegui.com\/en\/make-an-appointment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ionzabalegui.com\/en\/zabalegui-home\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.ionzabalegui.com\/en\/#website","url":"https:\/\/www.ionzabalegui.com\/en\/","name":"Zabalegui","description":"Medicina dental y facial","publisher":{"@id":"https:\/\/www.ionzabalegui.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ionzabalegui.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ionzabalegui.com\/en\/#organization","name":"Zabalegui","url":"https:\/\/www.ionzabalegui.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ionzabalegui.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ionzabalegui.com\/wp-content\/uploads\/2025\/04\/Icono-Ion-Zabalegui.png","contentUrl":"https:\/\/www.ionzabalegui.com\/wp-content\/uploads\/2025\/04\/Icono-Ion-Zabalegui.png","width":512,"height":512,"caption":"Zabalegui"},"image":{"@id":"https:\/\/www.ionzabalegui.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/pages\/17098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/comments?post=17098"}],"version-history":[{"count":4,"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/pages\/17098\/revisions"}],"predecessor-version":[{"id":18813,"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/pages\/17098\/revisions\/18813"}],"wp:attachment":[{"href":"https:\/\/www.ionzabalegui.com\/en\/wp-json\/wp\/v2\/media?parent=17098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}